{"id":2294,"date":"2018-07-01T16:13:53","date_gmt":"2018-07-01T13:13:53","guid":{"rendered":"https:\/\/blogavto.com\/2019-honda-insight-55-mpg-beast\/"},"modified":"2018-07-30T13:56:00","modified_gmt":"2018-07-30T10:56:00","slug":"2019-honda-insight-55-mpg-bestia","status":"publish","type":"post","link":"https:\/\/blogavto.com\/it\/2019-honda-insight-55-mpg-beast\/","title":{"rendered":"Honda Insight 2019: Bestia da 55 MPG"},"content":{"rendered":"<p>La Honda Insight Hybrid 2019 ha molta praticit\u00e0 e affidabilit\u00e0.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Indice dei contenuti<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Allinea la tabella dei contenuti\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/blogavto.com\/it\/2019-honda-insight-55-mpg-beast\/#%D0%9E%D1%81%D0%BE%D0%B1%D0%B5%D0%BD%D0%BD%D0%BE%D1%81%D1%82%D0%B8_%D0%BE%D1%82%D0%B4%D0%B5%D0%BB%D0%BA%D0%B8_%D1%81%D0%B0%D0%BB%D0%BE%D0%BD%D0%B0\" >Caratteristiche delle finiture interne<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/blogavto.com\/it\/2019-honda-insight-55-mpg-beast\/#%D0%9C%D0%BE%D1%89%D0%BD%D0%BE%D1%81%D1%82%D1%8C_%D0%B8_%D0%BF%D1%80%D0%BE%D0%B8%D0%B7%D0%B2%D0%BE%D0%B4%D0%B8%D1%82%D0%B5%D0%BB%D1%8C%D0%BD%D0%BE%D1%81%D1%82%D1%8C\" >Potenza e prestazioni<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/blogavto.com\/it\/2019-honda-insight-55-mpg-beast\/#%D0%A0%D0%B5%D0%B6%D0%B8%D0%BC%D1%8B_%D0%BF%D1%80%D0%B8%D0%B2%D0%BE%D0%B4%D0%B0_%D0%B8_%D1%80%D0%B0%D0%B7%D0%BC%D0%B5%D1%89%D0%B5%D0%BD%D0%B8%D0%B5_%D0%B1%D0%B0%D1%82%D0%B0%D1%80%D0%B5%D0%B9\" >Modalit\u00e0 di guida e posizionamento della batteria<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/blogavto.com\/it\/2019-honda-insight-55-mpg-beast\/#%D0%9F%D1%80%D0%BE%D0%B8%D0%B7%D0%B2%D0%BE%D0%B4%D1%81%D1%82%D0%B2%D0%BE_%D0%B8_%D1%86%D0%B5%D0%BD%D1%8B\" >Produzione e prezzi<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D0%9E%D1%81%D0%BE%D0%B1%D0%B5%D0%BD%D0%BD%D0%BE%D1%81%D1%82%D0%B8_%D0%BE%D1%82%D0%B4%D0%B5%D0%BB%D0%BA%D0%B8_%D1%81%D0%B0%D0%BB%D0%BE%D0%BD%D0%B0\"><\/span>Caratteristiche delle finiture interne<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Questa \u00e8 davvero un&#039;auto normale. Honda ritiene che i nuovi ibridi siano pi\u00f9 convenienti e verranno acquistati indipendentemente dall&#039;&quot;involucro&quot;.<\/p>\n<p>La Honda Insight 2019 colpisce nel segno con un prezzo economico che ti offre tre livelli di allestimento: LX, EX e Touring. Tutti i livelli sono dotati di fari a LED multi-elemento, avvio a pulsante e una suite di tecnologie avanzate Honda Sensing per la sicurezza del conducente.<\/p>\n<p>I prodotti Insight EX includono un display da otto pollici, un sistema audio con Apple CarPlay e Android Auto. L&#039;Insight Touring aggiunge sedili in pelle, otto posizioni dei sedili del conducente, il sistema di navigazione satellitare Honda e il climatizzatore automatico bizona.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/blogavto.com\/wp-content\/uploads\/images\/Honda_Insight_004-700x467.jpg\" alt=\"\" title=\"\"><br \/>\nHonda Insight 2019: Foto: Honda Nord America.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D0%9C%D0%BE%D1%89%D0%BD%D0%BE%D1%81%D1%82%D1%8C_%D0%B8_%D0%BF%D1%80%D0%BE%D0%B8%D0%B7%D0%B2%D0%BE%D0%B4%D0%B8%D1%82%D0%B5%D0%BB%D1%8C%D0%BD%D0%BE%D1%81%D1%82%D1%8C\"><\/span>Potenza e prestazioni<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>L&#039;Insight 2019 \u00e8 motivato dal propulsore ibrido bimotore di terza generazione di Honda. Il motore da 1,5 litri Inline-4 DOHC i-VTEC a ciclo Atkinson ha un 40.5% TEC. Questo GHIACCIO si accoppia con un motore elettrico, che sforna 197 libbre-piedi. di coppia e aggiunge 151 cavalli alle prestazioni complessive del sistema.<\/p>\n<p>Honda migliora ulteriormente il sistema di recupero dell&#039;energia con interruttori di decelerazione al volante. Questo \u00e8 simile al cambio di marcia e ti consente di passare tra tre diversi livelli di prestazioni di frenata rigenerativa. Honda afferma che il sistema non solo aumenta la durata della batteria attraverso la rigenerazione, ma aiuta anche a ridurre lo stress sui freni stessi, consentendo al pilota di adattare il proprio livello di frenata rigenerativa alle diverse condizioni.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/blogavto.com\/wp-content\/uploads\/images\/Honda_Insight_013-700x467.jpg\" alt=\"\" title=\"\"><br \/>\nFoto: Honda Nord America.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D0%A0%D0%B5%D0%B6%D0%B8%D0%BC%D1%8B_%D0%BF%D1%80%D0%B8%D0%B2%D0%BE%D0%B4%D0%B0_%D0%B8_%D1%80%D0%B0%D0%B7%D0%BC%D0%B5%D1%89%D0%B5%D0%BD%D0%B8%D0%B5_%D0%B1%D0%B0%D1%82%D0%B0%D1%80%D0%B5%D0%B9\"><\/span>Modalit\u00e0 di guida e posizionamento della batteria<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Il propulsore completamente ibrido dell&#039;Insight utilizza la potenza di tutti i sistemi (motore a benzina e motore elettrico) per fornire condizioni di guida.<\/p>\n<p>In una trasmissione ibrida, il motore a benzina aziona un generatore che fornisce elettricit\u00e0 al motore di trasmissione e, in determinate circostanze, il funzionamento del motore fa s\u00ec che il motore a benzina sia collegato direttamente alle ruote motrici.<\/p>\n<p>La batteria dell&#039;Insight 2019 si trova sotto i sedili posteriori. Grazie a ci\u00f2, l&#039;Insight sorprende con un impressionante 15,1 piedi cubi di spazio nel bagagliaio. Puoi ripiegare lo schienale del sedile posteriore per pi\u00f9 spazio di carico e lo spazio interno totale \u00e8 di 97,6 piedi cubi.<\/p>\n<p><img decoding=\"async\" class=\"alignleft\" src=\"https:\/\/blogavto.com\/wp-content\/uploads\/images\/Honda_Insight_006-200x200.jpg\" alt=\"\" title=\"\"><img decoding=\"async\" class=\"alignleft\" src=\"https:\/\/blogavto.com\/wp-content\/uploads\/images\/Honda_Insight_002-200x200.jpg\" alt=\"\" title=\"\"><img decoding=\"async\" class=\"alignleft\" src=\"https:\/\/blogavto.com\/wp-content\/uploads\/images\/Honda_Insight_001-200x200.jpg\" alt=\"\" title=\"\"><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D0%9F%D1%80%D0%BE%D0%B8%D0%B7%D0%B2%D0%BE%D0%B4%D1%81%D1%82%D0%B2%D0%BE_%D0%B8_%D1%86%D0%B5%D0%BD%D1%8B\"><\/span>Produzione e prezzi<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>L&#039;Insight 2019 \u00e8 prodotto nello stabilimento Honda di Greensburg, Indiana, mentre vengono costruiti il sistema a doppio motore Atkinson da 1,5 litri con sede in Ohio, il power pack intelligente e la batteria ibrida.<\/p>\n<p>Di seguito \u00e8 riportato un pratico grafico che mostra la ripartizione per Honda Insight 2019.<\/p>\n<table border=\"1\">\n<tbody>\n<tr>\n<td align=\"left\" valign=\"top\" width=\"145\">Finitura<\/td>\n<td align=\"center\" valign=\"top\" width=\"56\">Prezzo consigliato<\/td>\n<td align=\"center\" valign=\"top\" width=\"83\">Prezzo consigliato inclusa la destinazione $ 895<\/td>\n<td align=\"center\" valign=\"top\" width=\"153\">Classificazioni EPA sul risparmio di carburante (citt\u00e0\/autostrada\/combinata)<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"top\" width=\"145\">Approfondimento LX<\/td>\n<td align=\"center\" valign=\"top\" width=\"56\">$ 22830<\/td>\n<td align=\"center\" valign=\"top\" width=\"83\">$ 23725<\/td>\n<td align=\"center\" valign=\"top\" width=\"153\">55\/49\/52<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"top\" width=\"145\">Insight EX<\/td>\n<td align=\"center\" valign=\"top\" width=\"56\">$ 24060<\/td>\n<td align=\"center\" valign=\"top\" width=\"83\">$ 24995<\/td>\n<td align=\"center\" valign=\"top\" width=\"153\">55\/49\/52<\/td>\n<\/tr>\n<tr>\n<td align=\"left\" valign=\"top\" width=\"145\">Insight Touring<\/td>\n<td align=\"center\" valign=\"top\" width=\"56\">$ 28090<\/td>\n<td align=\"center\" valign=\"top\" width=\"83\">$ 28985<\/td>\n<td align=\"center\" valign=\"top\" width=\"153\">51\/45\/48<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Foto e fonte: Honda Nord America.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u0413\u0438\u0431\u0440\u0438\u0434 Honda Insight 2019 \u0433\u043e\u0434\u0430 \u043e\u0431\u043b\u0430\u0434\u0430\u0435\u0442 \u0431\u043e\u043b\u044c\u0448\u043e\u0439 \u043f\u0440\u0430\u043a\u0442\u0438\u0447\u043d\u043e\u0441\u0442\u044c\u044e \u0438 \u043d\u0430\u0434\u0435\u0436\u043d\u043e\u0441\u0442\u044c\u044e. \u041e\u0441\u043e\u0431\u0435\u043d\u043d\u043e\u0441\u0442\u0438 \u043e\u0442\u0434\u0435\u043b\u043a\u0438 \u0441\u0430\u043b\u043e\u043d\u0430 \u042d\u0442\u043e, \u0434\u0435\u0439\u0441\u0442\u0432\u0438\u0442\u0435\u043b\u044c\u043d\u043e, \u043d\u043e\u0440\u043c\u0430\u043b\u044c\u043d\u044b\u0439 \u0430\u0432\u0442\u043e\u043c\u043e\u0431\u0438\u043b\u044c. Honda \u0441\u0447\u0438\u0442\u0430\u0435\u0442, \u0447\u0442\u043e \u043d\u043e\u0432\u044b\u0435 \u0433\u0438\u0431\u0440\u0438\u0434\u044b \u0431\u043e\u043b\u0435\u0435 \u0443\u0434\u043e\u0431\u043d\u044b \u0438 \u043f\u043e\u043a\u0443\u043f\u0430\u0442\u044c \u0438\u0445 \u0431\u0443\u0434\u0443\u0442 \u043d\u0435\u0437\u0430\u0432\u0438\u0441\u0438\u043c\u043e \u043e\u0442 \u00ab\u043e\u0431\u0435\u0440\u0442\u043a\u0438\u00bb. Honda Insight 2019 \u043f\u043e\u0440\u0430\u0436\u0430\u0435\u0442 \u043d\u0435\u0434\u043e\u0440\u043e\u0433\u043e\u0439 \u0446\u0435\u043d\u043e\u0439, \u0437\u0430 \u043a\u043e\u0442\u043e\u0440\u0443\u044e \u0432\u044b \u043f\u043e\u043b\u0443\u0447\u0430\u0435\u0442\u0435 \u0442\u0440\u0438 \u0443\u0440\u043e\u0432\u043d\u044f \u043e\u0442\u0434\u0435\u043b\u043a\u0438 \u0441\u0430\u043b\u043e\u043d\u0430: LX, EX \u0438 Touring. \u0412\u0441\u0435 \u0443\u0440\u043e\u0432\u043d\u0438 \u043e\u0441\u043d\u0430\u0449\u0435\u043d\u044b \u043c\u043d\u043e\u0433\u043e\u044d\u043b\u0435\u043c\u0435\u043d\u0442\u043d\u044b\u043c\u0438 \u0441\u0432\u0435\u0442\u043e\u0434\u0438\u043e\u0434\u043d\u044b\u043c\u0438 \u0444\u0430\u0440\u0430\u043c\u0438, [&hellip;]<\/p>\n","protected":false},"author":495,"featured_media":2295,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2294","post","type-post","status-publish","format-standard","has-post-thumbnail","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogavto.com\/it\/wp-json\/wp\/v2\/posts\/2294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogavto.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogavto.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogavto.com\/it\/wp-json\/wp\/v2\/users\/495"}],"replies":[{"embeddable":true,"href":"https:\/\/blogavto.com\/it\/wp-json\/wp\/v2\/comments?post=2294"}],"version-history":[{"count":0,"href":"https:\/\/blogavto.com\/it\/wp-json\/wp\/v2\/posts\/2294\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogavto.com\/it\/wp-json\/wp\/v2\/media\/2295"}],"wp:attachment":[{"href":"https:\/\/blogavto.com\/it\/wp-json\/wp\/v2\/media?parent=2294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogavto.com\/it\/wp-json\/wp\/v2\/categories?post=2294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogavto.com\/it\/wp-json\/wp\/v2\/tags?post=2294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}