{"id":990,"date":"2018-05-01T17:27:33","date_gmt":"2018-05-01T14:27:33","guid":{"rendered":"https:\/\/blogavto.com\/%d0%bf%d0%b8%d1%81%d1%8c%d0%bc%d0%be-%d0%b8%d0%b7-%d0%b2%d0%b5%d0%bb%d0%b8%d0%ba%d0%be%d0%b1%d1%80%d0%b8%d1%82%d0%b0%d0%bd%d0%b8%d0%b8-%d0%bd%d0%b0%d0%bc-%d0%b4%d0%b0%d0%b6%d0%b5-%d0%bd%d1%83%d0%b6\/"},"modified":"2018-04-24T23:07:18","modified_gmt":"2018-04-24T20:07:18","slug":"d0-bf-d0-b8-d1-81-d1-8c-d0-bc-d0-be-d0-b8-d0-b7-d0-b2-d0-b5-d0-bb-d0-b8-d0-ba-d0-be-d0-b1-d1-80-d0-b8-d1-82-d0-b0-d0-bd-d0-b8-d0-b8-d0-bd-d0-b0-d0-bc-d0-b4-d0-b0-d0-b6-d0-b5-d0-bd-d1-83-d0-b6","status":"publish","type":"post","link":"https:\/\/blogavto.com\/uk\/d0-bf-d0-b8-d1-81-d1-8c-d0-bc-d0-be-d0-b8-d0-b7-d0-b2-d0-b5-d0-bb-d0-b8-d0-ba-d0-be-d0-b1-d1-80-d0-b8-d1-82-d0-b0-d0-bd-d0-b8-d0-b8-d0-bd-d0-b0-d0-bc-d0-b4-d0-b0-d0-b6-d0-b5-d0-bd-d1-83-d0-b6\/","title":{"rendered":"\u041b\u0438\u0441\u0442 \u0456\u0437 \u0412\u0435\u043b\u0438\u043a\u043e\u0431\u0440\u0438\u0442\u0430\u043d\u0456\u0457: \u043d\u0430\u043c \u043d\u0430\u0432\u0456\u0442\u044c \u043f\u043e\u0442\u0440\u0456\u0431\u043d\u0456 \u043d\u0430\u0448\u0456 \u043c\u0430\u0448\u0438\u043d\u0438?"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/blogavto.com\/wp-content\/uploads\/images\/Letter-from-the-UK.jpg\" alt=\"\" title=\"\"><\/p>\n<p>\u0412\u0435\u043b\u0438\u043a\u043e\u0431\u0440\u0438\u0442\u0430\u043d\u0438\u044f &#8212; \u043c\u0430\u043b\u0435\u043d\u044c\u043a\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0430. <\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0417\u043c\u0456\u0441\u0442<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/blogavto.com\/uk\/d0-bf-d0-b8-d1-81-d1-8c-d0-bc-d0-be-d0-b8-d0-b7-d0-b2-d0-b5-d0-bb-d0-b8-d0-ba-d0-be-d0-b1-d1-80-d0-b8-d1-82-d0-b0-d0-bd-d0-b8-d0-b8-d0-bd-d0-b0-d0-bc-d0-b4-d0-b0-d0-b6-d0-b5-d0-bd-d1-83-d0-b6\/#%D0%9E%D0%B1%D1%89%D0%B5%D1%81%D1%82%D0%B2%D0%B5%D0%BD%D0%BD%D1%8B%D0%B9_%D1%82%D1%80%D0%B0%D0%BD%D1%81%D0%BF%D0%BE%D1%80%D1%82_%D0%B2_%D0%92%D0%B5%D0%BB%D0%B8%D0%BA%D0%BE%D0%B1%D1%80%D0%B8%D1%82%D0%B0%D0%BD%D0%B8%D0%B8\" >\u041e\u0431\u0449\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0439 \u0442\u0440\u0430\u043d\u0441\u043f\u043e\u0440\u0442 \u0432 \u0412\u0435\u043b\u0438\u043a\u043e\u0431\u0440\u0438\u0442\u0430\u043d\u0438\u0438<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/blogavto.com\/uk\/d0-bf-d0-b8-d1-81-d1-8c-d0-bc-d0-be-d0-b8-d0-b7-d0-b2-d0-b5-d0-bb-d0-b8-d0-ba-d0-be-d0-b1-d1-80-d0-b8-d1-82-d0-b0-d0-bd-d0-b8-d0-b8-d0-bd-d0-b0-d0-bc-d0-b4-d0-b0-d0-b6-d0-b5-d0-bd-d1-83-d0-b6\/#%D0%9C%D1%8B_%D0%BF%D1%80%D0%BE%D1%82%D0%B8%D0%B2_%D0%BD%D0%B8%D1%85\" >\u041c\u044b \u043f\u0440\u043e\u0442\u0438\u0432 \u043d\u0438\u0445<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/blogavto.com\/uk\/d0-bf-d0-b8-d1-81-d1-8c-d0-bc-d0-be-d0-b8-d0-b7-d0-b2-d0-b5-d0-bb-d0-b8-d0-ba-d0-be-d0-b1-d1-80-d0-b8-d1-82-d0-b0-d0-bd-d0-b8-d0-b8-d0-bd-d0-b0-d0-bc-d0-b4-d0-b0-d0-b6-d0-b5-d0-bd-d1-83-d0-b6\/#%D0%BF%D1%80%D0%B8%D0%B2%D0%B0%D1%82%D0%B8%D0%B7%D0%B0%D1%86%D0%B8%D1%8F\" >\u043f\u0440\u0438\u0432\u0430\u0442\u0438\u0437\u0430\u0446\u0438\u044f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/blogavto.com\/uk\/d0-bf-d0-b8-d1-81-d1-8c-d0-bc-d0-be-d0-b8-d0-b7-d0-b2-d0-b5-d0-bb-d0-b8-d0-ba-d0-be-d0-b1-d1-80-d0-b8-d1-82-d0-b0-d0-bd-d0-b8-d0-b8-d0-bd-d0-b0-d0-bc-d0-b4-d0-b0-d0-b6-d0-b5-d0-bd-d1-83-d0-b6\/#%D0%90%D0%B2%D1%82%D0%BE%D0%BC%D0%BE%D0%B1%D0%B8%D0%BB%D1%8C%D0%BD%D1%8B%D0%B9_%D0%B0%D0%B2%D1%82%D0%BE%D0%BC%D0%BE%D0%B1%D0%B8%D0%BB%D1%8C\" >\u0410\u0432\u0442\u043e\u043c\u043e\u0431\u0438\u043b\u044c\u043d\u044b\u0439 \u0430\u0432\u0442\u043e\u043c\u043e\u0431\u0438\u043b\u044c<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/blogavto.com\/uk\/d0-bf-d0-b8-d1-81-d1-8c-d0-bc-d0-be-d0-b8-d0-b7-d0-b2-d0-b5-d0-bb-d0-b8-d0-ba-d0-be-d0-b1-d1-80-d0-b8-d1-82-d0-b0-d0-bd-d0-b8-d0-b8-d0-bd-d0-b0-d0-bc-d0-b4-d0-b0-d0-b6-d0-b5-d0-bd-d1-83-d0-b6\/#%D0%9F%D0%B5%D1%80%D0%B5%D1%81%D0%B5%D1%87%D0%B5%D0%BD%D0%B8%D0%B5_%D1%81%D1%82%D1%80%D0%B0%D0%BD%D1%8B\" >\u041f\u0435\u0440\u0435\u0441\u0435\u0447\u0435\u043d\u0438\u0435 \u0441\u0442\u0440\u0430\u043d\u044b<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%D0%9E%D0%B1%D1%89%D0%B5%D1%81%D1%82%D0%B2%D0%B5%D0%BD%D0%BD%D1%8B%D0%B9_%D1%82%D1%80%D0%B0%D0%BD%D1%81%D0%BF%D0%BE%D1%80%D1%82_%D0%B2_%D0%92%D0%B5%D0%BB%D0%B8%D0%BA%D0%BE%D0%B1%D1%80%D0%B8%D1%82%D0%B0%D0%BD%D0%B8%D0%B8\"><\/span>\u041e\u0431\u0449\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0439 \u0442\u0440\u0430\u043d\u0441\u043f\u043e\u0440\u0442 \u0432 \u0412\u0435\u043b\u0438\u043a\u043e\u0431\u0440\u0438\u0442\u0430\u043d\u0438\u0438<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0427\u0442\u043e \u0434\u043b\u044f \u043d\u0430\u0441 \u0441\u0434\u0435\u043b\u0430\u043b\u0438 \u0434\u0440\u0435\u0432\u043d\u0438\u0435 \u0440\u0438\u043c\u043b\u044f\u043d\u0435? <\/p>\n<p>\u0412 \u043e\u0442\u043b\u0438\u0447\u0438\u0435 \u043e\u0442 \u0410\u043c\u0435\u0440\u0438\u043a\u0438, \u0433\u0434\u0435 \u0441\u043e\u0437\u0434\u0430\u043d\u0438\u0435 \u043f\u0435\u0440\u0432\u043e\u0439 \u0442\u0440\u0430\u043d\u0441\u043a\u043e\u043d\u0442\u0438\u043d\u0435\u043d\u0442\u0430\u043b\u044c\u043d\u043e\u0439 \u0436\u0435\u043b\u0435\u0437\u043d\u043e\u0439 \u0434\u043e\u0440\u043e\u0433\u0438 \u0431\u044b\u043b\u043e \u0441\u043c\u0435\u043b\u044b\u043c \u0438 \u0441\u043b\u043e\u0436\u043d\u044b\u043c \u0438\u043d\u0436\u0435\u043d\u0435\u0440\u043d\u044b\u043c \u0447\u0443\u0434\u043e\u043c, \u0412\u0435\u043b\u0438\u043a\u043e\u0431\u0440\u0438\u0442\u0430\u043d\u0438\u044f \u043f\u0440\u0438 \u0438\u0437\u043e\u0431\u0440\u0435\u0442\u0435\u043d\u0438\u0438 \u0436\u0435\u043b\u0435\u0437\u043d\u043e\u0434\u043e\u0440\u043e\u0436\u043d\u043e\u0433\u043e \u0434\u0432\u0438\u0433\u0430\u0442\u0435\u043b\u044f \u0431\u044b\u0441\u0442\u0440\u043e \u0443\u0441\u0442\u0430\u043d\u043e\u0432\u0438\u043b\u0430 \u0436\u0435\u043b\u0435\u0437\u043d\u043e\u0434\u043e\u0440\u043e\u0436\u043d\u0443\u044e \u0441\u0435\u0442\u044c, \u043a\u043e\u0442\u043e\u0440\u0430\u044f \u0448\u043b\u0430 \u043f\u043e\u0432\u0441\u044e\u0434\u0443. <\/p>\n<p>\u0418 \u0432 \u0442\u0438\u043f\u0438\u0447\u043d\u043e\u0439 \u0431\u0440\u0438\u0442\u0430\u043d\u0441\u043a\u043e\u0439 \u043c\u043e\u0434\u0435 \u043c\u044b \u043f\u043e\u0433\u0443\u0431\u0438\u043b\u0438 \u0435\u0435.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D0%9C%D1%8B_%D0%BF%D1%80%D0%BE%D1%82%D0%B8%D0%B2_%D0%BD%D0%B8%D1%85\"><\/span>\u041c\u044b \u043f\u0440\u043e\u0442\u0438\u0432 \u043d\u0438\u0445<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>20-\u0439 \u0432\u0435\u043a \u043f\u0440\u0438\u043d\u0435\u0441 \u0441 \u0441\u043e\u0431\u043e\u0439 \u043c\u043e\u0433\u0443\u0447\u0438\u0439 \u043f\u043e\u0434\u044a\u0435\u043c \u0432\u043b\u0430\u0441\u0442\u0438 \u0440\u0430\u0437\u043b\u0438\u0447\u043d\u044b\u0445 \u043f\u0440\u043e\u0444\u0441\u043e\u044e\u0437\u043e\u0432, \u0438 \u0440\u0430\u0431\u043e\u0447\u0438\u0435 \u0442\u0440\u0435\u0431\u043e\u0432\u0430\u043b\u0438 \u0432\u0441\u0435 \u0431\u043e\u043b\u044c\u0448\u0435 \u0438 \u0431\u043e\u043b\u044c\u0448\u0435 \u043f\u0440\u0430\u0432 \u0438 \u0434\u0435\u043d\u0435\u0433. <\/p>\n<p>\u0418\u0437-\u0437\u0430 \u044d\u0442\u043e\u0433\u043e \u0438\u043d\u0444\u0440\u0430\u0441\u0442\u0440\u0443\u043a\u0442\u0443\u0440\u0430 \u043e\u0431\u0449\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0433\u043e \u0442\u0440\u0430\u043d\u0441\u043f\u043e\u0440\u0442\u0430 \u0431\u044b\u0441\u0442\u0440\u043e \u0441\u043e\u043a\u0440\u0430\u0449\u0430\u043b\u0430\u0441\u044c \u0431\u043b\u0430\u0433\u043e\u0434\u0430\u0440\u044f \u0441\u043e\u0447\u0435\u0442\u0430\u043d\u0438\u044e \u043d\u0435\u0443\u043c\u0435\u043b\u044b\u0445 \u0431\u043e\u0441\u0441\u043e\u0432, \u0443\u0441\u0442\u0430\u0440\u0435\u0432\u0448\u0438\u0445 \u0430\u0432\u0442\u043e\u0431\u0443\u0441\u043e\u0432 \u0438 \u043f\u043e\u0434\u0432\u0438\u0436\u043d\u043e\u0433\u043e \u0441\u043e\u0441\u0442\u0430\u0432\u0430, \u0433\u0440\u044f\u0437\u043d\u044b\u0445 \u0441\u0442\u0430\u043d\u0446\u0438\u0439 \u0438 \u0442\u0435\u0440\u043c\u0438\u043d\u0430\u043b\u043e\u0432 \u0438 \u043f\u0435\u0440\u0441\u043e\u043d\u0430\u043b\u0430, \u043a\u043e\u0442\u043e\u0440\u044b\u0439 \u043d\u0435 \u043c\u043e\u0433 \u043d\u0430\u043f\u043b\u0435\u0432\u0430\u0442\u044c. <\/p>\n<p>\u0417\u0430\u0442\u0435\u043c \u043f\u043e\u044f\u0432\u0438\u043b\u0430\u0441\u044c \u0416\u0435\u043b\u0435\u0437\u043d\u0430\u044f \u041b\u0435\u0434\u0438: \u041c\u0430\u0440\u0433\u0430\u0440\u0435\u0442 \u0422\u044d\u0442\u0447\u0435\u0440.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/blogavto.com\/wp-content\/uploads\/images\/colorful-underground-subway-train-with-blurry-PVBR3FK-700x467.jpg\" alt=\"\" title=\"\"><\/p>\n<p>\u041f\u043e \u0434\u0430\u043d\u043d\u044b\u043c \u0410\u043c\u0435\u0440\u0438\u043a\u0430\u043d\u0441\u043a\u043e\u0439 \u0430\u0441\u0441\u043e\u0446\u0438\u0430\u0446\u0438\u0438 \u043e\u0431\u0449\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0433\u043e \u0442\u0440\u0430\u043d\u0441\u043f\u043e\u0440\u0442\u0430, \u0431\u043e\u043b\u0435\u0435 6800 \u043e\u0440\u0433\u0430\u043d\u0438\u0437\u0430\u0446\u0438\u0439 \u043f\u0440\u0435\u0434\u043e\u0441\u0442\u0430\u0432\u043b\u044f\u044e\u0442 \u043e\u0431\u0449\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0439 \u0442\u0440\u0430\u043d\u0441\u043f\u043e\u0440\u0442 \u0432 \u0421\u043e\u0435\u0434\u0438\u043d\u0435\u043d\u043d\u044b\u0445 \u0428\u0442\u0430\u0442\u0430\u0445. <\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D0%BF%D1%80%D0%B8%D0%B2%D0%B0%D1%82%D0%B8%D0%B7%D0%B0%D1%86%D0%B8%D1%8F\"><\/span>\u043f\u0440\u0438\u0432\u0430\u0442\u0438\u0437\u0430\u0446\u0438\u044f<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u041d\u0430\u0448 \u043f\u0440\u0435\u043c\u044c\u0435\u0440-\u043c\u0438\u043d\u0438\u0441\u0442\u0440 \u0432 1980-\u0445 \u0433\u043e\u0434\u0430\u0445 \u0440\u0435\u0448\u0438\u043b, \u0447\u0442\u043e \u043d\u0435\u043e\u0431\u0445\u043e\u0434\u0438\u043c\u043e, \u0447\u0442\u043e\u0431\u044b \u0442\u0440\u0430\u043d\u0441\u043f\u043e\u0440\u0442\u043d\u044b\u0435 \u0443\u0441\u043b\u0443\u0433\u0438 \u0431\u044b\u043b\u0438 \u043f\u0440\u043e\u0434\u0430\u043d\u044b \u0441\u0430\u043c\u044b\u043c \u0432\u044b\u0441\u043e\u043a\u0438\u043c \u0443\u0447\u0430\u0441\u0442\u043d\u0438\u043a\u0430\u043c \u0442\u043e\u0440\u0433\u043e\u0432. <\/p>\n<p>\u041d\u0430\u043c \u043d\u0443\u0436\u043d\u043e \u0431\u044b\u043b\u043e. <\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D0%90%D0%B2%D1%82%D0%BE%D0%BC%D0%BE%D0%B1%D0%B8%D0%BB%D1%8C%D0%BD%D1%8B%D0%B9_%D0%B0%D0%B2%D1%82%D0%BE%D0%BC%D0%BE%D0%B1%D0%B8%D0%BB%D1%8C\"><\/span>\u0410\u0432\u0442\u043e\u043c\u043e\u0431\u0438\u043b\u044c\u043d\u044b\u0439 \u0430\u0432\u0442\u043e\u043c\u043e\u0431\u0438\u043b\u044c<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0423 \u043d\u0430\u0441 \u043f\u0440\u043e\u0446\u0432\u0435\u0442\u0430\u044e\u0449\u0430\u044f \u0430\u0432\u0442\u043e\u043c\u043e\u0431\u0438\u043b\u044c\u043d\u0430\u044f \u0438\u043d\u0434\u0443\u0441\u0442\u0440\u0438\u044f, \u043a\u043e\u0442\u043e\u0440\u0430\u044f \u043e\u0445\u0432\u0430\u0442\u044b\u0432\u0430\u0435\u0442 \u0432\u0435\u0441\u044c \u0437\u0435\u043c\u043d\u043e\u0439 \u0448\u0430\u0440. <\/p>\n<p>\u041e\u043d\u0438 \u043f\u043e\u0434\u043b\u0435\u0436\u0430\u0442 \u043d\u0430\u043b\u043e\u0433\u043e\u043e\u0431\u043b\u043e\u0436\u0435\u043d\u0438\u044e, \u043a\u043e\u0433\u0434\u0430 \u043c\u044b \u043f\u043e\u043a\u0443\u043f\u0430\u0435\u043c \u0438\u0445, \u043a\u043e\u0433\u0434\u0430 \u043c\u044b \u0432\u044b\u0441\u0442\u0430\u0432\u043b\u044f\u0435\u043c \u0438\u0445 \u043d\u0430 \u0434\u043e\u0440\u043e\u0433\u0443, \u043a\u043e\u0433\u0434\u0430 \u043c\u044b \u043d\u0430\u043f\u043e\u043b\u043d\u044f\u0435\u043c \u0438\u0445 \u0442\u043e\u043f\u043b\u0438\u0432\u043e\u043c, \u0438 \u043a\u043e\u0433\u0434\u0430 \u043c\u044b \u0438\u0445 \u0437\u0430\u0441\u0442\u0440\u0430\u0445\u043e\u0432\u044b\u0432\u0430\u0435\u043c. <\/p>\n<p>\u041a\u043e\u043d\u0435\u0447\u043d\u043e, \u043b\u044e\u0434\u0438, \u043e\u0441\u043e\u0431\u0435\u043d\u043d\u043e \u043c\u043e\u043b\u043e\u0434\u044b\u0435, \u0436\u0438\u0432\u0443\u0449\u0438\u0435 \u0432 \u0433\u043e\u0440\u043e\u0434\u0441\u043a\u0438\u0445 \u0440\u0430\u0439\u043e\u043d\u0430\u0445, \u043f\u0440\u0435\u0434\u0432\u0435\u0449\u0430\u044e\u0442 \u0430\u0432\u0442\u043e \u0432 \u043f\u043e\u043b\u044c\u0437\u0443 \u043e\u0431\u0449\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0433\u043e \u0442\u0440\u0430\u043d\u0441\u043f\u043e\u0440\u0442\u0430. <\/p>\n<p><img decoding=\"async\" src=\"https:\/\/blogavto.com\/wp-content\/uploads\/images\/Uber-Passengers-India--700x394.jpg\" alt=\"\" title=\"\"><\/p>\n<p>\u041f\u0430\u0441\u0441\u0430\u0436\u0438\u0440\u044b Uber \u043a\u0430\u0442\u0430\u044e\u0442\u0441\u044f \u0432 \u0418\u043d\u0434\u0438\u0438. <\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D0%9F%D0%B5%D1%80%D0%B5%D1%81%D0%B5%D1%87%D0%B5%D0%BD%D0%B8%D0%B5_%D1%81%D1%82%D1%80%D0%B0%D0%BD%D1%8B\"><\/span>\u041f\u0435\u0440\u0435\u0441\u0435\u0447\u0435\u043d\u0438\u0435 \u0441\u0442\u0440\u0430\u043d\u044b<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0411\u0435\u0434\u0430 \u0432 \u0442\u043e\u043c, \u0447\u0442\u043e \u043c\u043d\u0435 \u043d\u0440\u0430\u0432\u0438\u0442\u0441\u044f \u043f\u0443\u0442\u0435\u0448\u0435\u0441\u0442\u0432\u043e\u0432\u0430\u0442\u044c \u0438 \u0432\u0438\u0434\u0435\u0442\u044c \u043d\u043e\u0432\u044b\u0435 \u043c\u0435\u0441\u0442\u0430. <\/p>\n<p>\u041a\u0430\u0436\u0435\u0442\u0441\u044f, \u044f \u043f\u0440\u043e\u0441\u0442\u043e \u043e\u0442\u0432\u0435\u0442\u0438\u043b \u043d\u0430 \u0441\u0432\u043e\u0439 \u0432\u043e\u043f\u0440\u043e\u0441.<\/p>\n<p>\u0414\u0436\u0435\u0444\u0444 \u041c\u0430\u0441\u0442\u0435\u0434 \u2014 \u043f\u0438\u0441\u044c\u043c\u0435\u043d\u043d\u0438\u043a, \u0444\u043e\u0442\u043e\u0433\u0440\u0430\u0444 \u0442\u0430 \u0430\u0432\u0442\u043e\u0440 \u043d\u0430\u0448\u043e\u0457 \u0441\u0435\u0440\u0456\u0457 \u00ab\u041b\u0438\u0441\u0442 \u0456\u0437 \u0412\u0435\u043b\u0438\u043a\u043e\u0457 \u0411\u0440\u0438\u0442\u0430\u043d\u0456\u0457\u00bb. <\/p>","protected":false},"excerpt":{"rendered":"<p>\u0412\u0435\u043b\u0438\u043a\u043e\u0431\u0440\u0438\u0442\u0430\u043d\u0438\u044f &#8212; \u043c\u0430\u043b\u0435\u043d\u044c\u043a\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0430. \u041e\u0431\u0449\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0439 \u0442\u0440\u0430\u043d\u0441\u043f\u043e\u0440\u0442 \u0432 \u0412\u0435\u043b\u0438\u043a\u043e\u0431\u0440\u0438\u0442\u0430\u043d\u0438\u0438 \u0427\u0442\u043e \u0434\u043b\u044f \u043d\u0430\u0441 \u0441\u0434\u0435\u043b\u0430\u043b\u0438 \u0434\u0440\u0435\u0432\u043d\u0438\u0435 \u0440\u0438\u043c\u043b\u044f\u043d\u0435? \u0412 \u043e\u0442\u043b\u0438\u0447\u0438\u0435 \u043e\u0442 \u0410\u043c\u0435\u0440\u0438\u043a\u0438, \u0433\u0434\u0435 \u0441\u043e\u0437\u0434\u0430\u043d\u0438\u0435 \u043f\u0435\u0440\u0432\u043e\u0439 \u0442\u0440\u0430\u043d\u0441\u043a\u043e\u043d\u0442\u0438\u043d\u0435\u043d\u0442\u0430\u043b\u044c\u043d\u043e\u0439 \u0436\u0435\u043b\u0435\u0437\u043d\u043e\u0439 \u0434\u043e\u0440\u043e\u0433\u0438 \u0431\u044b\u043b\u043e \u0441\u043c\u0435\u043b\u044b\u043c \u0438 \u0441\u043b\u043e\u0436\u043d\u044b\u043c \u0438\u043d\u0436\u0435\u043d\u0435\u0440\u043d\u044b\u043c \u0447\u0443\u0434\u043e\u043c, \u0412\u0435\u043b\u0438\u043a\u043e\u0431\u0440\u0438\u0442\u0430\u043d\u0438\u044f \u043f\u0440\u0438 \u0438\u0437\u043e\u0431\u0440\u0435\u0442\u0435\u043d\u0438\u0438 \u0436\u0435\u043b\u0435\u0437\u043d\u043e\u0434\u043e\u0440\u043e\u0436\u043d\u043e\u0433\u043e \u0434\u0432\u0438\u0433\u0430\u0442\u0435\u043b\u044f \u0431\u044b\u0441\u0442\u0440\u043e \u0443\u0441\u0442\u0430\u043d\u043e\u0432\u0438\u043b\u0430 \u0436\u0435\u043b\u0435\u0437\u043d\u043e\u0434\u043e\u0440\u043e\u0436\u043d\u0443\u044e \u0441\u0435\u0442\u044c, \u043a\u043e\u0442\u043e\u0440\u0430\u044f \u0448\u043b\u0430 \u043f\u043e\u0432\u0441\u044e\u0434\u0443. \u0418 \u0432 \u0442\u0438\u043f\u0438\u0447\u043d\u043e\u0439 \u0431\u0440\u0438\u0442\u0430\u043d\u0441\u043a\u043e\u0439 \u043c\u043e\u0434\u0435 \u043c\u044b \u043f\u043e\u0433\u0443\u0431\u0438\u043b\u0438 \u0435\u0435. \u041c\u044b \u043f\u0440\u043e\u0442\u0438\u0432 \u043d\u0438\u0445 20-\u0439 \u0432\u0435\u043a [&hellip;]<\/p>\n","protected":false},"author":495,"featured_media":991,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[295],"tags":[],"class_list":["post-990","post","type-post","status-publish","format-standard","has-post-thumbnail","category-vozhdenie"],"_links":{"self":[{"href":"https:\/\/blogavto.com\/uk\/wp-json\/wp\/v2\/posts\/990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogavto.com\/uk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogavto.com\/uk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogavto.com\/uk\/wp-json\/wp\/v2\/users\/495"}],"replies":[{"embeddable":true,"href":"https:\/\/blogavto.com\/uk\/wp-json\/wp\/v2\/comments?post=990"}],"version-history":[{"count":0,"href":"https:\/\/blogavto.com\/uk\/wp-json\/wp\/v2\/posts\/990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogavto.com\/uk\/wp-json\/wp\/v2\/media\/991"}],"wp:attachment":[{"href":"https:\/\/blogavto.com\/uk\/wp-json\/wp\/v2\/media?parent=990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogavto.com\/uk\/wp-json\/wp\/v2\/categories?post=990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogavto.com\/uk\/wp-json\/wp\/v2\/tags?post=990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}